{"id":30209,"date":"2026-02-07T16:18:34","date_gmt":"2026-02-07T08:18:34","guid":{"rendered":"https:\/\/avantcashmere.com\/?post_type=product&#038;p=30209"},"modified":"2026-04-18T21:15:36","modified_gmt":"2026-04-18T13:15:36","slug":"avant-logo-socks","status":"publish","type":"product","link":"https:\/\/avantcashmere.com\/en\/product\/avant-logo-socks\/","title":{"rendered":"Wool Logo Socks \/ A\u0432\u0430\u043d\u0442 \u043b\u043e\u0433\u043e\u0442\u043e\u0439 \u043e\u0439\u043c\u0441"},"content":{"rendered":"<p>50% \u043d\u043e\u043e\u0441 50% \u0430\u043a\u0440\u0438\u043b\u043a \u0445\u043e\u043b\u044c\u0446\u0442\u043e\u0439\u00a0 \u0443\u0442\u0441\u0430\u0430\u0440, whole garment \u043c\u0430\u0448\u0438\u043d \u0434\u044d\u044d\u0440 \u043e\u0451\u0434\u043e\u043b\u0433\u04af\u0439\u0433\u044d\u044d\u0440 \u0441\u04af\u043b\u0436\u0438\u0433\u0434\u0441\u044d\u043d, \u0441\u0443\u043d\u0430\u043b\u0442 \u0441\u0430\u0439\u0442\u0430\u0439 \u043e\u0439\u043c\u0441. <\/p>\n<p><strong>\u04e8\u043d\u0433\u04e9:<\/strong><\/p>\n<ul>\n<li>\u0426\u0430\u0439\u0432\u0430\u0440 \u043a\u0440\u0435\u043c<\/li>\n<li>\u0425\u0430\u0440<\/li>\n<li>\u0426\u0430\u0439\u0432\u0430\u0440 \u0446\u044d\u043d\u0445\u044d\u0440<\/li>\n<\/ul>\n<p><strong>\u041e\u043d\u0446\u043b\u043e\u0433:<\/strong><\/p>\n<ul>\n<li>26\/2 wool blend \u0443\u0442\u0430\u0441 \u2013 \u0430\u0440\u044c\u0441\u0430\u043d\u0434 \u0437\u04e9\u04e9\u043b\u04e9\u043d, \u0437\u0430\u0433\u0442\u043d\u0443\u0443\u043b\u0430\u0445\u0433\u04af\u0439<\/li>\n<li>10gg whole garment \u0442\u0435\u0445\u043d\u043e\u043b\u043e\u0433\u0438 \u2013 \u043e\u0451\u0434\u043e\u043b\u0433\u04af\u0439, \u0442\u0430\u0432 \u0442\u0443\u0445\u0442\u0430\u0439 \u04e9\u043c\u0441\u0433\u04e9\u043b<\/li>\n<li>\u0413\u0443\u044f \u0445\u04af\u0440\u0441\u044d\u043d \u0443\u0440\u0442 \u2013 \u0445\u04e9\u043b\u043d\u0438\u0439 \u0448\u0443\u0433\u0430\u043c\u044b\u0433 \u0443\u0440\u0442\u0430\u0441\u0433\u0430\u043d, \u043d\u0430\u0440\u0438\u0439\u0445\u0430\u043d \u0445\u0430\u0440\u0430\u0433\u0434\u0443\u0443\u043b\u043d\u0430<\/li>\n<li>\u0421\u0443\u043d\u0430\u043b\u0442 \u0441\u0430\u0439\u0442\u0430\u0439 \u2013 \u0445\u044d\u043b\u0431\u044d\u0440\u044d\u044d \u0441\u0430\u0439\u043d \u0431\u0430\u0440\u0438\u043d\u0430<\/li>\n<li>\u041b\u043e\u0433\u043e\u0442\u043e\u0439 \u0436\u0438\u0436\u0438\u0433 \u043f\u0430\u0439\u0437\u0442\u0430\u0439, \u043c\u0438\u043d\u0438\u043c\u0430\u043b \u0434\u0438\u0437\u0430\u0439\u043d \u2013 \u04e9\u0434\u04e9\u0440 \u0442\u0443\u0442\u0430\u043c \u0431\u043e\u043b\u043e\u043d city look-\u0434 \u0442\u043e\u0445\u0438\u0440\u043e\u043c\u0436\u0442\u043e\u0439<\/li>\n<\/ul>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-25181\" src=\"http:\/\/avantcashmere.com\/wp-content\/uploads\/2024\/05\/untitled-100-x-50-px-3.png\" alt=\"\" width=\"1000\" height=\"500\" srcset=\"https:\/\/avantcashmere.com\/wp-content\/uploads\/2024\/05\/untitled-100-x-50-px-3.png 1000w, https:\/\/avantcashmere.com\/wp-content\/uploads\/2024\/05\/untitled-100-x-50-px-3-640x320.png 640w, https:\/\/avantcashmere.com\/wp-content\/uploads\/2024\/05\/untitled-100-x-50-px-3-768x384.png 768w, https:\/\/avantcashmere.com\/wp-content\/uploads\/2024\/05\/untitled-100-x-50-px-3-400x200.png 400w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>50% \u043d\u043e\u043e\u0441 50% \u0430\u043a\u0440\u0438\u043b\u043a \u0445\u043e\u043b\u044c\u0446\u0442\u043e\u0439\u00a0 \u0443\u0442\u0441\u0430\u0430\u0440, whole garment \u043c\u0430\u0448\u0438\u043d \u0434\u044d\u044d\u0440 \u043e\u0451\u0434\u043e\u043b\u0433\u04af\u0439\u0433\u044d\u044d\u0440 \u0441\u04af\u043b\u0436\u0438\u0433\u0434\u0441\u044d\u043d, \u0441\u0443\u043d\u0430\u043b\u0442 \u0441\u0430\u0439\u0442\u0430\u0439 \u043e\u0439\u043c\u0441. \u04e8\u043d\u0433\u04e9: \u0426\u0430\u0439\u0432\u0430\u0440 \u043a\u0440\u0435\u043c \u0425\u0430\u0440 \u0426\u0430\u0439\u0432\u0430\u0440 \u0446\u044d\u043d\u0445\u044d\u0440 \u041e\u043d\u0446\u043b\u043e\u0433: 26\/2 wool blend \u0443\u0442\u0430\u0441 \u2013 \u0430\u0440\u044c\u0441\u0430\u043d\u0434 \u0437\u04e9\u04e9\u043b\u04e9\u043d, \u0437\u0430\u0433\u0442\u043d\u0443\u0443\u043b\u0430\u0445\u0433\u04af\u0439 10gg whole garment \u0442\u0435\u0445\u043d\u043e\u043b\u043e\u0433\u0438 \u2013 \u043e\u0451\u0434\u043e\u043b\u0433\u04af\u0439, \u0442\u0430\u0432 \u0442\u0443\u0445\u0442\u0430\u0439 \u04e9\u043c\u0441\u0433\u04e9\u043b \u0413\u0443\u044f \u0445\u04af\u0440\u0441\u044d\u043d \u0443\u0440\u0442 \u2013 \u0445\u04e9\u043b\u043d\u0438\u0439 \u0448\u0443\u0433\u0430\u043c\u044b\u0433 \u0443\u0440\u0442\u0430\u0441\u0433\u0430\u043d, \u043d\u0430\u0440\u0438\u0439\u0445\u0430\u043d \u0445\u0430\u0440\u0430\u0433\u0434\u0443\u0443\u043b\u043d\u0430 \u0421\u0443\u043d\u0430\u043b\u0442 \u0441\u0430\u0439\u0442\u0430\u0439 \u2013 \u0445\u044d\u043b\u0431\u044d\u0440\u044d\u044d \u0441\u0430\u0439\u043d \u0431\u0430\u0440\u0438\u043d\u0430 \u041b\u043e\u0433\u043e\u0442\u043e\u0439 [&hellip;]<\/p>\n","protected":false},"featured_media":30228,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[216,260,220,46],"product_tag":[761,764,762],"giftcard-category":[],"class_list":{"0":"post-30209","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-accessories","7":"product_cat-basic-collection","8":"product_cat-accessories-socks","9":"product_cat-women","10":"product_tag-gift","11":"product_tag-home-wear","12":"product_tag-casual","14":"first","15":"instock","16":"taxable","17":"shipping-taxable","18":"purchasable","19":"product-type-variable","20":"has-default-attributes"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.6 (Yoast SEO v24.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Wool Blend Logo Socks for Women | Avant Cashmere<\/title>\n<meta name=\"description\" content=\"Wool blend socks for women | Avant Cashmere \u2014 Mongolian luxury since 2015. Ships worldwide.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/avantcashmere.com\/product\/avant-logo-socks\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wool Logo Socks \/ A\u0432\u0430\u043d\u0442 \u043b\u043e\u0433\u043e\u0442\u043e\u0439 \u043e\u0439\u043c\u0441\" \/>\n<meta property=\"og:description\" content=\"Wool Logo Socks \/ A\u0432\u0430\u043d\u0442 \u043b\u043e\u0433\u043e\u0442\u043e\u0439 \u043e\u0439\u043c\u0441 - Avant Cashmere - 100% Mongolian fine Cashmere , whole sales available. Ship to worldwide\" \/>\n<meta property=\"og:url\" content=\"https:\/\/avantcashmere.com\/product\/avant-logo-socks\/\" \/>\n<meta property=\"og:site_name\" content=\"Avant Cashmere\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/avantmongolia\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-18T13:15:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/avantcashmere.com\/wp-content\/uploads\/2026\/02\/DSC00961_Edited.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1331\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@avantcashmere\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/avantcashmere.com\/product\/avant-logo-socks\/\",\"url\":\"https:\/\/avantcashmere.com\/product\/avant-logo-socks\/\",\"name\":\"Wool Blend Logo Socks for Women | Avant Cashmere\",\"isPartOf\":{\"@id\":\"https:\/\/avantcashmere.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/avantcashmere.com\/product\/avant-logo-socks\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/avantcashmere.com\/product\/avant-logo-socks\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/avantcashmere.com\/wp-content\/uploads\/2026\/02\/DSC00961_Edited.jpg\",\"datePublished\":\"2026-02-07T08:18:34+00:00\",\"dateModified\":\"2026-04-18T13:15:36+00:00\",\"description\":\"Wool blend socks for women | Avant Cashmere \u2014 Mongolian luxury since 2015. Ships worldwide.\",\"breadcrumb\":{\"@id\":\"https:\/\/avantcashmere.com\/product\/avant-logo-socks\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/avantcashmere.com\/product\/avant-logo-socks\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/avantcashmere.com\/product\/avant-logo-socks\/#primaryimage\",\"url\":\"https:\/\/avantcashmere.com\/wp-content\/uploads\/2026\/02\/DSC00961_Edited.jpg\",\"contentUrl\":\"https:\/\/avantcashmere.com\/wp-content\/uploads\/2026\/02\/DSC00961_Edited.jpg\",\"width\":1600,\"height\":1331,\"caption\":\"Wool blend socks for women - lifestyle | Avant Cashmere\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/avantcashmere.com\/product\/avant-logo-socks\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/avantcashmere.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/avantcashmere.com\/en\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Wool Logo Socks \/ A\u0432\u0430\u043d\u0442 \u043b\u043e\u0433\u043e\u0442\u043e\u0439 \u043e\u0439\u043c\u0441\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/avantcashmere.com\/en\/#website\",\"url\":\"https:\/\/avantcashmere.com\/en\/\",\"name\":\"Avant Cashmere\",\"description\":\"Mongolian Cashmere\",\"publisher\":{\"@id\":\"https:\/\/avantcashmere.com\/en\/#organization\"},\"alternateName\":\"Avant Mongolia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/avantcashmere.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/avantcashmere.com\/en\/#organization\",\"name\":\"Avant Clothing LLC\",\"alternateName\":\"Avant\",\"url\":\"https:\/\/avantcashmere.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/avantcashmere.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/avantcashmere.com\/wp-content\/uploads\/2022\/09\/logo.png\",\"contentUrl\":\"https:\/\/avantcashmere.com\/wp-content\/uploads\/2022\/09\/logo.png\",\"width\":136,\"height\":18,\"caption\":\"Avant Clothing LLC\"},\"image\":{\"@id\":\"https:\/\/avantcashmere.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/avantmongolia\/\",\"https:\/\/x.com\/avantcashmere\",\"https:\/\/www.instagram.com\/avant.cashmere.wool\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Wool Blend Logo Socks for Women | Avant Cashmere","description":"Wool blend socks for women | Avant Cashmere \u2014 Mongolian luxury since 2015. Ships worldwide.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/avantcashmere.com\/product\/avant-logo-socks\/","og_locale":"en_US","og_type":"article","og_title":"Wool Logo Socks \/ A\u0432\u0430\u043d\u0442 \u043b\u043e\u0433\u043e\u0442\u043e\u0439 \u043e\u0439\u043c\u0441","og_description":"Wool Logo Socks \/ A\u0432\u0430\u043d\u0442 \u043b\u043e\u0433\u043e\u0442\u043e\u0439 \u043e\u0439\u043c\u0441 - Avant Cashmere - 100% Mongolian fine Cashmere , whole sales available. Ship to worldwide","og_url":"https:\/\/avantcashmere.com\/product\/avant-logo-socks\/","og_site_name":"Avant Cashmere","article_publisher":"https:\/\/www.facebook.com\/avantmongolia\/","article_modified_time":"2026-04-18T13:15:36+00:00","og_image":[{"width":1600,"height":1331,"url":"https:\/\/avantcashmere.com\/wp-content\/uploads\/2026\/02\/DSC00961_Edited.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@avantcashmere","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/avantcashmere.com\/product\/avant-logo-socks\/","url":"https:\/\/avantcashmere.com\/product\/avant-logo-socks\/","name":"Wool Blend Logo Socks for Women | Avant Cashmere","isPartOf":{"@id":"https:\/\/avantcashmere.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/avantcashmere.com\/product\/avant-logo-socks\/#primaryimage"},"image":{"@id":"https:\/\/avantcashmere.com\/product\/avant-logo-socks\/#primaryimage"},"thumbnailUrl":"https:\/\/avantcashmere.com\/wp-content\/uploads\/2026\/02\/DSC00961_Edited.jpg","datePublished":"2026-02-07T08:18:34+00:00","dateModified":"2026-04-18T13:15:36+00:00","description":"Wool blend socks for women | Avant Cashmere \u2014 Mongolian luxury since 2015. Ships worldwide.","breadcrumb":{"@id":"https:\/\/avantcashmere.com\/product\/avant-logo-socks\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/avantcashmere.com\/product\/avant-logo-socks\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/avantcashmere.com\/product\/avant-logo-socks\/#primaryimage","url":"https:\/\/avantcashmere.com\/wp-content\/uploads\/2026\/02\/DSC00961_Edited.jpg","contentUrl":"https:\/\/avantcashmere.com\/wp-content\/uploads\/2026\/02\/DSC00961_Edited.jpg","width":1600,"height":1331,"caption":"Wool blend socks for women - lifestyle | Avant Cashmere"},{"@type":"BreadcrumbList","@id":"https:\/\/avantcashmere.com\/product\/avant-logo-socks\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/avantcashmere.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/avantcashmere.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Wool Logo Socks \/ A\u0432\u0430\u043d\u0442 \u043b\u043e\u0433\u043e\u0442\u043e\u0439 \u043e\u0439\u043c\u0441"}]},{"@type":"WebSite","@id":"https:\/\/avantcashmere.com\/en\/#website","url":"https:\/\/avantcashmere.com\/en\/","name":"Avant Cashmere","description":"Mongolian Cashmere","publisher":{"@id":"https:\/\/avantcashmere.com\/en\/#organization"},"alternateName":"Avant Mongolia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/avantcashmere.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/avantcashmere.com\/en\/#organization","name":"Avant Clothing LLC","alternateName":"Avant","url":"https:\/\/avantcashmere.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/avantcashmere.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/avantcashmere.com\/wp-content\/uploads\/2022\/09\/logo.png","contentUrl":"https:\/\/avantcashmere.com\/wp-content\/uploads\/2022\/09\/logo.png","width":136,"height":18,"caption":"Avant Clothing LLC"},"image":{"@id":"https:\/\/avantcashmere.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/avantmongolia\/","https:\/\/x.com\/avantcashmere","https:\/\/www.instagram.com\/avant.cashmere.wool"]}]}},"_links":{"self":[{"href":"https:\/\/avantcashmere.com\/en\/wp-json\/wp\/v2\/product\/30209","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avantcashmere.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/avantcashmere.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/avantcashmere.com\/en\/wp-json\/wp\/v2\/comments?post=30209"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/avantcashmere.com\/en\/wp-json\/wp\/v2\/media\/30228"}],"wp:attachment":[{"href":"https:\/\/avantcashmere.com\/en\/wp-json\/wp\/v2\/media?parent=30209"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/avantcashmere.com\/en\/wp-json\/wp\/v2\/product_brand?post=30209"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/avantcashmere.com\/en\/wp-json\/wp\/v2\/product_cat?post=30209"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/avantcashmere.com\/en\/wp-json\/wp\/v2\/product_tag?post=30209"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/avantcashmere.com\/en\/wp-json\/wp\/v2\/giftcard-category?post=30209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}